{"id":2082,"date":"2022-06-21T15:11:03","date_gmt":"2022-06-21T13:11:03","guid":{"rendered":"https:\/\/www.nameshield.com\/en\/?page_id=2082"},"modified":"2023-12-15T10:52:29","modified_gmt":"2023-12-15T09:52:29","slug":"goodies","status":"publish","type":"page","link":"https:\/\/www.nameshield.com\/en\/goodies\/","title":{"rendered":"Goodies"},"content":{"rendered":"\n<div class=\" wp-block-cover alignfull eplus-wrapper\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-neve-link-hover-color-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div style=\"height:80px\" aria-hidden=\"true\" class=\" wp-block-spacer eplus-wrapper\"><\/div>\n\n\n<div class=\"wp-block-columns alignwide eplus-wrapper is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex eplus-styles-uid-add242\">\n<div class=\"wp-block-column eplus-wrapper is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image \">\n<figure class=\"alignleft size-large eplus-wrapper\"><a href=\"https:\/\/www.nameshield.com\/wp-content\/uploads\/2023\/12\/phishing_winter_2024.jpg\"><img decoding=\"async\" src=\"https:\/\/www.nameshield.com\/wp-content\/uploads\/2023\/12\/phishing_winter_2024-1024x576.jpg\" alt class=\"wp-image-7689\"><\/a><\/figure>\n<\/div>\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\" wp-block-spacer eplus-wrapper\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center eplus-wrapper is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\" wp-block-heading has-text-align-center has-nv-text-dark-bg-color has-text-color eplus-wrapper\">New wallpaper Phishing!<\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\" wp-block-spacer eplus-wrapper\"><\/div>\n\n\n\n<div class=\"wp-block-buttons eplus-wrapper is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-7d812b4c wp-block-buttons-is-layout-flex\"><div class=\"is-style-secondary wp-block-button eplus-wrapper eplus-styles-uid-ebebea\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.nameshield.com\/wp-content\/uploads\/2023\/12\/phishing_winter_2024.jpg\" target=\"_blank\" rel=\"noreferrer noopener\">Download the wall\u00adpa\u00adper<\/a><\/div><\/div>\n\n\n\n<p class=\"eplus-wrapper wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\" wp-block-spacer eplus-wrapper\"><\/div>\n<\/div><\/div>\n\n\n\n<div class=\" wp-block-cover alignfull eplus-wrapper\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-nv-light-bg-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div style=\"height:80px\" aria-hidden=\"true\" class=\" wp-block-spacer eplus-wrapper\"><\/div>\n\n\n<div class=\"wp-block-columns alignwide eplus-wrapper is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex eplus-styles-uid-b2e20f\">\n<div class=\"wp-block-column eplus-wrapper is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image \">\n<figure class=\"alignleft size-large eplus-wrapper\"><a href=\"https:\/\/www.nameshield.com\/wp-content\/uploads\/2022\/06\/phishing_summer2022_fond_ecran-1.png\"><img decoding=\"async\" src=\"https:\/\/www.nameshield.com\/wp-content\/uploads\/2022\/06\/phishing_summer2022_fond_ecran-1-1024x576.png\" alt=\"Phishing summer 2022 wallpaper\" class=\"wp-image-6830\"><\/a><\/figure>\n<\/div>\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\" wp-block-spacer eplus-wrapper\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center eplus-wrapper is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\" wp-block-heading has-text-align-center has-neve-text-color-color has-text-color eplus-wrapper\">Phishing summer<\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\" wp-block-spacer eplus-wrapper\"><\/div>\n\n\n\n<div class=\"wp-block-buttons eplus-wrapper is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-7d812b4c wp-block-buttons-is-layout-flex\"><div class=\"is-style-secondary wp-block-button eplus-wrapper eplus-styles-uid-2d6175\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.nameshield.com\/wp-content\/uploads\/2022\/06\/phishing_summer2022_fond_ecran-1.png\" target=\"_blank\" rel=\"noreferrer noopener\">Download the wall\u00adpa\u00adper<\/a><\/div><\/div>\n\n\n\n<p class=\"eplus-wrapper wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\" wp-block-spacer eplus-wrapper\"><\/div>\n<\/div><\/div>\n\n\n\n<div class=\" wp-block-cover alignfull eplus-wrapper\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-neve-link-hover-color-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div style=\"height:80px\" aria-hidden=\"true\" class=\" wp-block-spacer eplus-wrapper\"><\/div>\n\n\n<div class=\"wp-block-columns alignwide eplus-wrapper is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex eplus-styles-uid-88addb\">\n<div class=\"wp-block-column eplus-wrapper is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image \">\n<figure class=\"alignleft size-large eplus-wrapper\"><a href=\"https:\/\/www.nameshield.com\/wp-content\/uploads\/2022\/12\/fond-d-ecran-phishing-on-winter-holyday.png\"><img decoding=\"async\" src=\"https:\/\/www.nameshield.com\/wp-content\/uploads\/2022\/12\/fond-d-ecran-phishing-on-winter-holyday-1024x576.png\" alt=\"Fond d'\u00e9cran phishing durant les vacances d'hiver\" class=\"wp-image-7151\"><\/a><\/figure>\n<\/div>\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\" wp-block-spacer eplus-wrapper\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center eplus-wrapper is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\" wp-block-heading has-text-align-center has-nv-text-dark-bg-color has-text-color eplus-wrapper\">Phishing winter<\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\" wp-block-spacer eplus-wrapper\"><\/div>\n\n\n\n<div class=\"wp-block-buttons eplus-wrapper is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-7d812b4c wp-block-buttons-is-layout-flex\"><div class=\"is-style-secondary wp-block-button eplus-wrapper eplus-styles-uid-6921b3\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.nameshield.com\/wp-content\/uploads\/2022\/12\/fond-d-ecran-phishing-on-winter-holyday.png\" target=\"_blank\" rel=\"noreferrer noopener\">Download the wall\u00adpa\u00adper<\/a><\/div><\/div>\n\n\n\n<p class=\"eplus-wrapper wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\" wp-block-spacer eplus-wrapper\"><\/div>\n<\/div><\/div>\n\n\n\n<div class=\" wp-block-cover alignfull eplus-wrapper\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-nv-c-2-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div style=\"height:80px\" aria-hidden=\"true\" class=\" wp-block-spacer eplus-wrapper\"><\/div>\n\n\n<div class=\"wp-block-columns alignwide eplus-wrapper is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex eplus-styles-uid-468a09\">\n<div class=\"wp-block-column eplus-wrapper is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image \">\n<figure class=\"alignleft size-large eplus-wrapper\"><a href=\"https:\/\/www.nameshield.com\/wp-content\/uploads\/2021\/12\/phishing_noel.png\"><img decoding=\"async\" src=\"https:\/\/www.nameshield.com\/wp-content\/uploads\/2021\/12\/phishing_noel-1024x576.png\" alt=\"Christmas Phishing  wallpaper\" class=\"wp-image-6305\"><\/a><\/figure>\n<\/div>\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\" wp-block-spacer eplus-wrapper\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center eplus-wrapper is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\" wp-block-heading has-text-align-center has-nv-text-dark-bg-color has-text-color eplus-wrapper\">Christmas Phishing <\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\" wp-block-spacer eplus-wrapper\"><\/div>\n\n\n\n<div class=\"wp-block-buttons eplus-wrapper is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-7d812b4c wp-block-buttons-is-layout-flex\"><div class=\"is-style-secondary wp-block-button eplus-wrapper eplus-styles-uid-b8cca1\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.nameshield.com\/wp-content\/uploads\/2021\/12\/phishing_noel.png\" target=\"_blank\" rel=\"noreferrer noopener\">Download the wall\u00adpa\u00adper<\/a><\/div><\/div>\n\n\n\n<p class=\"eplus-wrapper wp-block-paragraph\"><\/p>\n<\/div>\n<\/div>\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\" wp-block-spacer eplus-wrapper\"><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"wp_typography_post_enhancements_disabled":false,"editor_plus_copied_stylings":"{}","_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"neve_meta_sidebar":"full-width","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"class_list":["post-2082","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Goodies - Nameshield<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nameshield.com\/en\/goodies\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Goodies - Nameshield\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nameshield.com\/en\/goodies\/\" \/>\n<meta property=\"og:site_name\" content=\"Nameshield\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-15T09:52:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nameshield.com\/wp-content\/uploads\/2023\/12\/phishing_winter_2024-1024x576.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nameshield.com\\\/en\\\/goodies\\\/\",\"url\":\"https:\\\/\\\/www.nameshield.com\\\/en\\\/goodies\\\/\",\"name\":\"Goodies - Nameshield\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nameshield.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nameshield.com\\\/en\\\/goodies\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nameshield.com\\\/en\\\/goodies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nameshield.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/phishing_winter_2024-1024x576.jpg\",\"datePublished\":\"2022-06-21T13:11:03+00:00\",\"dateModified\":\"2023-12-15T09:52:29+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nameshield.com\\\/en\\\/goodies\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.nameshield.com\\\/en\\\/goodies\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nameshield.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/phishing_winter_2024-1024x576.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nameshield.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/phishing_winter_2024-1024x576.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nameshield.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.nameshield.com\\\/en\\\/\",\"name\":\"Nameshield\",\"description\":\"Online Assets Security\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nameshield.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Goodies - Nameshield","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nameshield.com\/en\/goodies\/","og_locale":"en_US","og_type":"article","og_title":"Goodies - Nameshield","og_url":"https:\/\/www.nameshield.com\/en\/goodies\/","og_site_name":"Nameshield","article_modified_time":"2023-12-15T09:52:29+00:00","og_image":[{"url":"https:\/\/www.nameshield.com\/wp-content\/uploads\/2023\/12\/phishing_winter_2024-1024x576.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nameshield.com\/en\/goodies\/","url":"https:\/\/www.nameshield.com\/en\/goodies\/","name":"Goodies - Nameshield","isPartOf":{"@id":"https:\/\/www.nameshield.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nameshield.com\/en\/goodies\/#primaryimage"},"image":{"@id":"https:\/\/www.nameshield.com\/en\/goodies\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nameshield.com\/wp-content\/uploads\/2023\/12\/phishing_winter_2024-1024x576.jpg","datePublished":"2022-06-21T13:11:03+00:00","dateModified":"2023-12-15T09:52:29+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nameshield.com\/en\/goodies\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nameshield.com\/en\/goodies\/#primaryimage","url":"https:\/\/www.nameshield.com\/wp-content\/uploads\/2023\/12\/phishing_winter_2024-1024x576.jpg","contentUrl":"https:\/\/www.nameshield.com\/wp-content\/uploads\/2023\/12\/phishing_winter_2024-1024x576.jpg"},{"@type":"WebSite","@id":"https:\/\/www.nameshield.com\/en\/#website","url":"https:\/\/www.nameshield.com\/en\/","name":"Nameshield","description":"Online Assets Security","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nameshield.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.nameshield.com\/en\/wp-json\/wp\/v2\/pages\/2082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nameshield.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.nameshield.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.nameshield.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nameshield.com\/en\/wp-json\/wp\/v2\/comments?post=2082"}],"version-history":[{"count":7,"href":"https:\/\/www.nameshield.com\/en\/wp-json\/wp\/v2\/pages\/2082\/revisions"}],"predecessor-version":[{"id":2388,"href":"https:\/\/www.nameshield.com\/en\/wp-json\/wp\/v2\/pages\/2082\/revisions\/2388"}],"wp:attachment":[{"href":"https:\/\/www.nameshield.com\/en\/wp-json\/wp\/v2\/media?parent=2082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}